{"id":13441,"date":"2022-09-07T21:26:07","date_gmt":"2022-09-07T19:26:07","guid":{"rendered":"https:\/\/cinevillastudios.com\/event-gallery\/compensa-2022\/"},"modified":"2024-07-10T12:55:10","modified_gmt":"2024-07-10T10:55:10","slug":"compensa-2022","status":"publish","type":"event-gallery","link":"https:\/\/cinevillastudios.com\/ko\/event-gallery\/compensa-2022\/","title":{"rendered":"COMPENSA 2022"},"content":{"rendered":"\n<script type=\"text\/javascript\" src=\"https:\/\/failiem.lv\/gallery_module\/v1\/js\/?hash=cq5xh5k2q&#038;user=714b7f9&#038;ihash=468bc46cbb67bb03315d0566ce097422&#038;view=horizontal\" id=\"files_fm_upload_script_tag\"><\/script>\n","protected":false},"featured_media":0,"template":"","class_list":["post-13441","event-gallery","type-event-gallery","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COMPENSA 2022 - Cinevilla Studio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cinevillastudios.com\/ko\/event-gallery\/compensa-2022\/\" \/>\n<meta property=\"og:locale\" content=\"ko_KR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMPENSA 2022 - Cinevilla Studio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cinevillastudios.com\/ko\/event-gallery\/compensa-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Cinevilla Studio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Cinevilla\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-10T10:55:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cinevillastudios.com\\\/ko\\\/event-gallery\\\/compensa-2022\\\/\",\"url\":\"https:\\\/\\\/cinevillastudios.com\\\/ko\\\/event-gallery\\\/compensa-2022\\\/\",\"name\":\"COMPENSA 2022 - Cinevilla Studio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cinevillastudios.com\\\/ko\\\/#website\"},\"datePublished\":\"2022-09-07T19:26:07+00:00\",\"dateModified\":\"2024-07-10T10:55:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cinevillastudios.com\\\/ko\\\/event-gallery\\\/compensa-2022\\\/#breadcrumb\"},\"inLanguage\":\"ko-KR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cinevillastudios.com\\\/ko\\\/event-gallery\\\/compensa-2022\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cinevillastudios.com\\\/ko\\\/event-gallery\\\/compensa-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cinevillastudios.com\\\/ko\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COMPENSA 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cinevillastudios.com\\\/ko\\\/#website\",\"url\":\"https:\\\/\\\/cinevillastudios.com\\\/ko\\\/\",\"name\":\"Cinevilla Studio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cinevillastudios.com\\\/ko\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cinevillastudios.com\\\/ko\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ko-KR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cinevillastudios.com\\\/ko\\\/#organization\",\"name\":\"Cinevilla Studio\",\"url\":\"https:\\\/\\\/cinevillastudios.com\\\/ko\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ko-KR\",\"@id\":\"https:\\\/\\\/cinevillastudios.com\\\/ko\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cinevillastudios.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cinevilla-studio-logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/cinevillastudios.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cinevilla-studio-logo-1.svg\",\"width\":182,\"height\":144,\"caption\":\"Cinevilla Studio\"},\"image\":{\"@id\":\"https:\\\/\\\/cinevillastudios.com\\\/ko\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Cinevilla\",\"https:\\\/\\\/www.instagram.com\\\/cinevillastudios\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMPENSA 2022 - Cinevilla Studio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cinevillastudios.com\/ko\/event-gallery\/compensa-2022\/","og_locale":"ko_KR","og_type":"article","og_title":"COMPENSA 2022 - Cinevilla Studio","og_url":"https:\/\/cinevillastudios.com\/ko\/event-gallery\/compensa-2022\/","og_site_name":"Cinevilla Studio","article_publisher":"https:\/\/www.facebook.com\/Cinevilla","article_modified_time":"2024-07-10T10:55:10+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cinevillastudios.com\/ko\/event-gallery\/compensa-2022\/","url":"https:\/\/cinevillastudios.com\/ko\/event-gallery\/compensa-2022\/","name":"COMPENSA 2022 - Cinevilla Studio","isPartOf":{"@id":"https:\/\/cinevillastudios.com\/ko\/#website"},"datePublished":"2022-09-07T19:26:07+00:00","dateModified":"2024-07-10T10:55:10+00:00","breadcrumb":{"@id":"https:\/\/cinevillastudios.com\/ko\/event-gallery\/compensa-2022\/#breadcrumb"},"inLanguage":"ko-KR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cinevillastudios.com\/ko\/event-gallery\/compensa-2022\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cinevillastudios.com\/ko\/event-gallery\/compensa-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cinevillastudios.com\/ko\/"},{"@type":"ListItem","position":2,"name":"COMPENSA 2022"}]},{"@type":"WebSite","@id":"https:\/\/cinevillastudios.com\/ko\/#website","url":"https:\/\/cinevillastudios.com\/ko\/","name":"Cinevilla Studio","description":"","publisher":{"@id":"https:\/\/cinevillastudios.com\/ko\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cinevillastudios.com\/ko\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ko-KR"},{"@type":"Organization","@id":"https:\/\/cinevillastudios.com\/ko\/#organization","name":"Cinevilla Studio","url":"https:\/\/cinevillastudios.com\/ko\/","logo":{"@type":"ImageObject","inLanguage":"ko-KR","@id":"https:\/\/cinevillastudios.com\/ko\/#\/schema\/logo\/image\/","url":"https:\/\/cinevillastudios.com\/wp-content\/uploads\/2023\/08\/cinevilla-studio-logo-1.svg","contentUrl":"https:\/\/cinevillastudios.com\/wp-content\/uploads\/2023\/08\/cinevilla-studio-logo-1.svg","width":182,"height":144,"caption":"Cinevilla Studio"},"image":{"@id":"https:\/\/cinevillastudios.com\/ko\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Cinevilla","https:\/\/www.instagram.com\/cinevillastudios\/"]}]}},"_links":{"self":[{"href":"https:\/\/cinevillastudios.com\/ko\/wp-json\/wp\/v2\/event-gallery\/13441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinevillastudios.com\/ko\/wp-json\/wp\/v2\/event-gallery"}],"about":[{"href":"https:\/\/cinevillastudios.com\/ko\/wp-json\/wp\/v2\/types\/event-gallery"}],"wp:attachment":[{"href":"https:\/\/cinevillastudios.com\/ko\/wp-json\/wp\/v2\/media?parent=13441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}